{"id":866,"date":"2020-09-21T08:45:58","date_gmt":"2020-09-21T08:45:58","guid":{"rendered":"http:\/\/grupo.farmaciastrebol.com\/?p=866"},"modified":"2022-12-14T08:17:42","modified_gmt":"2022-12-14T08:17:42","slug":"la-homeopatia-un-aliado-de-la-cistitis","status":"publish","type":"post","link":"https:\/\/www.farmaciastrebol.com\/grupo\/2020\/09\/21\/la-homeopatia-un-aliado-de-la-cistitis\/","title":{"rendered":"La homeopat\u00eda, un aliado de la cistitis"},"content":{"rendered":"<p>Las infecciones urinarias no son una patolog\u00eda que deba pasarse por alto y tomarse a la ligera, ya que al ser descuidadas o mal tratadas pueden provocar problemas mayores, sobre todo en los ri\u00f1ones. Es muy importante recordar que estas afecciones son ocasionadas por la invasi\u00f3n de microorganismos en el tracto urinario, lo que genera molestias y necesidad frecuente de orinar.<\/p>\n<p><!--more--><\/p>\n<p>Las infecciones m\u00e1s habituales son generadas por bacterias aunque tambi\u00e9n pueden presentarse a causa de virus, hongos o par\u00e1sitos. El responsable de muchas de ellas es el microbio Escherichia Coli, que normalmente vive en el intestino.<\/p>\n<p>Ante las primeras molestias es fundamental acudir al m\u00e9dico para que nos prescriba un tratamiento. Es aqu\u00ed donde la <a href=\"http:\/\/www.webconsultas.com\/belleza-y-bienestar\/terapias-alternativas\/homeopatia-2552\" target=\"_blank\" style=\"color:#7aa52b;font-weight:bold\" rel=\"noopener\">homeopat\u00eda<\/a> puede ser de utilidad para tratar la sintomatolog\u00eda asociada a esta enfermedad, de acuerdo con el perfil del paciente. Esta terapia puede ser una herramienta \u00fatil en el tratamiento tanto de los episodios agudos como en el caso de los pacientes que recaen frecuentemente en este tipo de infecciones.<\/p>\n<p>La elecci\u00f3n de alguno de estos medicamentos depender\u00e1 de las caracter\u00edsticas de cada paciente y del problema que presente. Ser\u00e1 el profesional sanitario el encargado de dise\u00f1ar el tratamiento a seguir y de determinar si debe suministrarse el f\u00e1rmaco homeop\u00e1tico de forma complementaria a un posible tratamiento con antibi\u00f3tico, o bien en exclusiva. Hasta la fecha, no se han descrito interacciones entre los medicamentos homeop\u00e1ticos y otros medicamentos.<\/p>\n<p>La homeopat\u00eda puede resultar una opci\u00f3n de tratamiento a tener en cuenta por el paciente porque no valora s\u00f3lo los s\u00edntomas propios de la infecci\u00f3n, como son el aumento de la frecuencia miccional (polaquiuria), el dolor al orinar (disuria) o la necesidad constante de orinar, se valora tambi\u00e9n aspectos personales y singulares del paciente.<\/p>\n<p>El doctor Jos\u00e9 Manuel Garc\u00eda, especialista en medicina intensiva destaca que la realizaci\u00f3n de los estudios para diagnosticar esta infecci\u00f3n urinaria depender\u00e1 de las caracter\u00edsticas y gravedad del paciente, aunque los de rutina son el examen f\u00edsico y an\u00e1lisis de orina. Una vez confirmado el diagn\u00f3stico, los especialistas elegir\u00e1n los tratamientos personalizados para cada paciente, ya que no todos deben seguir el mismo.<\/p>\n<p>Asimismo ha remarcado que el tratamiento deber\u00e1 acompa\u00f1arse de una dieta equilibrada, un consumo de dos litros de agua al d\u00eda y una adecuada higiene tras ir al ba\u00f1o y durante la ducha. La hidrataci\u00f3n constante es tambi\u00e9n una manera excelente de prevenir la cistitis, pues con la orina se expulsan esas sustancias nocivas que pueden ocasionarla. Es aconsejable, por tanto, acudir al ba\u00f1o cada dos o tres horas.<\/p>\n<div class=\"links\">\n <a href=\"#comments\">Comentarios (0)<\/a> |<br \/>\n <a href=\"#trackbacks\">Trackbacks (0)<\/a> |<br \/>\n <a href=\"\/blog\/la-homeopatia-un-aliado-de-la-cistitis\">Permalink<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las infecciones urinarias no son una patolog\u00eda que deba pasarse por alto y tomarse a la ligera, ya que al ser descuidadas o mal tratadas pueden provocar problemas mayores, sobre todo en los ri\u00f1ones. Es muy importante recordar que estas afecciones son ocasionadas por la invasi\u00f3n de microorganismos en el tracto urinario, lo que genera [&hellip;]<\/p>\n","protected":false},"author":937,"featured_media":8105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,80,97],"tags":[728,729,730,291,722,724,725,726,727],"class_list":["post-866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","category-medicamentos","category-homeopatia","tag-eventos-de-salud-y-bienestar","tag-servicios-trebol","tag-terapia-natural-y-homeopatia","tag-deporte","tag-nutricion-y-dietetica","tag-atencion-farmaceutica","tag-cosmetica-y-belleza","tag-bebes-y-ninos","tag-embarazo-y-lactancia"],"aioseo_notices":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.farmaciastrebol.com\/grupo\/wp-json\/wp\/v2\/posts\/866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.farmaciastrebol.com\/grupo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.farmaciastrebol.com\/grupo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.farmaciastrebol.com\/grupo\/wp-json\/wp\/v2\/users\/937"}],"replies":[{"embeddable":true,"href":"https:\/\/www.farmaciastrebol.com\/grupo\/wp-json\/wp\/v2\/comments?post=866"}],"version-history":[{"count":3,"href":"https:\/\/www.farmaciastrebol.com\/grupo\/wp-json\/wp\/v2\/posts\/866\/revisions"}],"predecessor-version":[{"id":20185,"href":"https:\/\/www.farmaciastrebol.com\/grupo\/wp-json\/wp\/v2\/posts\/866\/revisions\/20185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.farmaciastrebol.com\/grupo\/wp-json\/wp\/v2\/media\/8105"}],"wp:attachment":[{"href":"https:\/\/www.farmaciastrebol.com\/grupo\/wp-json\/wp\/v2\/media?parent=866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.farmaciastrebol.com\/grupo\/wp-json\/wp\/v2\/categories?post=866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.farmaciastrebol.com\/grupo\/wp-json\/wp\/v2\/tags?post=866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}